{"id":8939,"date":"2024-09-28T12:24:05","date_gmt":"2024-09-28T10:24:05","guid":{"rendered":"https:\/\/www.johannstrauss2025.at\/artist\/leonard-erod\/"},"modified":"2025-06-02T14:40:15","modified_gmt":"2025-06-02T12:40:15","slug":"leonard-erod","status":"publish","type":"artist","link":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/","title":{"rendered":"Leonard Er\u00f6d"},"content":{"rendered":"","protected":false},"featured_media":8940,"template":"","meta":{"_acf_changed":true},"function":[421],"class_list":["post-8939","artist","type-artist","status-publish","has-post-thumbnail","hentry","function-arrangement-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leonard Er\u00f6d - Johann Strauss 2025 Wien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leonard Er\u00f6d - Johann Strauss 2025 Wien\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/\" \/>\n<meta property=\"og:site_name\" content=\"Johann Strauss 2025 Wien\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/johannstrauss25\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T12:40:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/11\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/\",\"url\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/\",\"name\":\"Leonard Er\u00f6d - Johann Strauss 2025 Wien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg\",\"datePublished\":\"2024-09-28T10:24:05+00:00\",\"dateModified\":\"2025-06-02T12:40:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg\",\"width\":624,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/artist\\\/leonard-erod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leonard Er\u00f6d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/\",\"name\":\"Johann Strauss 2025 Wien\",\"description\":\"Wien feiert 200 Jahre Johann Strauss - vom 1. J\u00e4nner bis 31. Dezember 2025. Und zwar mit einer Premiere w\u00f6chentlich. Aus zehn verschiedenen Genres, Indoor wie Open Air.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#organization\",\"name\":\"Johann Strauss 2025 Wien\",\"url\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/JOST-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/JOST-logo.png\",\"width\":622,\"height\":240,\"caption\":\"Johann Strauss 2025 Wien\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johannstrauss2025.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/johannstrauss25\\\/\",\"https:\\\/\\\/www.instagram.com\\\/johannstrauss2025\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leonard Er\u00f6d - Johann Strauss 2025 Wien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/","og_locale":"en_US","og_type":"article","og_title":"Leonard Er\u00f6d - Johann Strauss 2025 Wien","og_url":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/","og_site_name":"Johann Strauss 2025 Wien","article_publisher":"https:\/\/www.facebook.com\/johannstrauss25\/","article_modified_time":"2025-06-02T12:40:15+00:00","og_image":[{"width":624,"height":800,"url":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/11\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/","url":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/","name":"Leonard Er\u00f6d - Johann Strauss 2025 Wien","isPartOf":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/#primaryimage"},"image":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/11\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg","datePublished":"2024-09-28T10:24:05+00:00","dateModified":"2025-06-02T12:40:15+00:00","breadcrumb":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/#primaryimage","url":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/11\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg","contentUrl":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/11\/LeonardEroed_credits_Tom_Mesic_komprimiert.jpg","width":624,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.johannstrauss2025.at\/en\/artist\/leonard-erod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.johannstrauss2025.at\/en\/"},{"@type":"ListItem","position":2,"name":"Leonard Er\u00f6d"}]},{"@type":"WebSite","@id":"https:\/\/www.johannstrauss2025.at\/en\/#website","url":"https:\/\/www.johannstrauss2025.at\/en\/","name":"Johann Strauss 2025 Wien","description":"Wien feiert 200 Jahre Johann Strauss - vom 1. J\u00e4nner bis 31. Dezember 2025. Und zwar mit einer Premiere w\u00f6chentlich. Aus zehn verschiedenen Genres, Indoor wie Open Air.","publisher":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johannstrauss2025.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.johannstrauss2025.at\/en\/#organization","name":"Johann Strauss 2025 Wien","url":"https:\/\/www.johannstrauss2025.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.johannstrauss2025.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/10\/JOST-logo.png","contentUrl":"https:\/\/www.johannstrauss2025.at\/wp-content\/uploads\/2024\/10\/JOST-logo.png","width":622,"height":240,"caption":"Johann Strauss 2025 Wien"},"image":{"@id":"https:\/\/www.johannstrauss2025.at\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/johannstrauss25\/","https:\/\/www.instagram.com\/johannstrauss2025\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/artist\/8939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/types\/artist"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/media\/8940"}],"wp:attachment":[{"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/media?parent=8939"}],"wp:term":[{"taxonomy":"function","embeddable":true,"href":"https:\/\/www.johannstrauss2025.at\/en\/wp-json\/wp\/v2\/function?post=8939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}